{"id":6195,"date":"2018-10-12T13:38:17","date_gmt":"2018-10-12T17:38:17","guid":{"rendered":"https:\/\/www.presbyterianfoundation.org\/?p=6195"},"modified":"2024-07-16T16:11:10","modified_gmt":"2024-07-16T20:11:10","slug":"el-presbiterio-de-carolina-costera-se-recupera-del-huracan-florence","status":"publish","type":"post","link":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/","title":{"rendered":"El Presbiterio de Carolina del Costa se recupera del hurac\u00e1n"},"content":{"rendered":"<p><a href=\"http:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/1-roadside-debris.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6197 size-medium\" src=\"http:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/1-roadside-debris-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Congregaciones eclesi\u00e1sticas de todo el mundo <a href=\"http:\/\/presbycc.org\/\">Presbiterio de Carolina del Costa<\/a> luchan por reparar sus propios edificios y atender las numerosas necesidades de sus congregaciones y comunidades tras el paso del hurac\u00e1n Florence.<\/p>\n<p>La devastaci\u00f3n es generalizada, dijo la Rev. Dra. Nancy Gladden, que sirve como Coordinadora de Misi\u00f3n para la Comunidad del Este en el Presbiterio de Carolina Costera. El Presbiterio de Carolina Costera abarca la mitad sur de la costa de Carolina del Norte y es uno de los cinco presbiterios de Carolina del Norte.<\/p>\n<p>Gladden cree que con un poco de apoyo adicional, las iglesias, sus congregaciones y comunidades pueden recuperarse m\u00e1s r\u00e1pidamente. El Presbiterio puso en marcha esta semana un fondo de donaciones en l\u00ednea con la Fundaci\u00f3n Presbiteriana para recibir donativos con los que poder ayudar a las iglesias a preparar el espacio para los grupos de trabajo y distribuir suministros a quienes los necesiten. Presbyterian Disaster Assistance tambi\u00e9n ha estado trabajando con el Presbiterio para ayudar con la estrategia, organizaci\u00f3n y log\u00edstica de la recuperaci\u00f3n. Gladden dijo que el Presbiterio est\u00e1 agradecido por la ayuda de PDA.<\/p>\n<p>El fondo en l\u00ednea establecido por el Presbiterio de la Costa de Carolina le permitir\u00e1 aceptar donaciones r\u00e1pidamente y, con suerte, evitar\u00e1 los esfuerzos bien intencionados de enviar \"cosas\", que pueden resultar m\u00e1s una carga que una ayuda. El dinero le da al Presbiterio flexibilidad para satisfacer necesidades inmediatas. Si desea apoyar al Presbiterio, puede hacerlo <a href=\"https:\/\/www.eservicepayments.com\/cgi-bin\/Vanco_ver3.vps?appver3=wWsk24ZWJSTZKsGd1RMKlg0BDvsSG3VIWQCPJNNxD8upkiY7JlDavDsozUE7KG0nFx2NSo8LdUKGuGuF396vbR4nnsPYluSkcUA2WGlyScyXHubq5Z7ap5JVmPErc4ZeYHCKCZhESjGNQmZ5B-6dx4BGn5VPX4EXGa9q_kVlmeo=&amp;ver=3\">aqu\u00ed<\/a>.<\/p>\n<p>Las donaciones monetarias tambi\u00e9n pueden suponer un impulso econ\u00f3mico, especialmente en las ciudades peque\u00f1as y rurales. \"Si las donaciones pueden gastarse en las comunidades locales, pueden ayudar a la econom\u00eda local en las zonas que han sufrido da\u00f1os tan graves\", afirma Nancy Gladden.<\/p>\n<p><strong>Una mirada m\u00e1s atenta a las congregaciones<\/strong><\/p>\n<p>Varios pastores del este de Carolina del Norte del PC (EE.UU.) proporcionaron una mirada m\u00e1s cercana a las necesidades en sus iglesias y comunidades. En Morehead City, el reverendo Tim Havlicek, pastor de la Primera Iglesia Presbiteriana, dice que la propia iglesia sufri\u00f3 algunos da\u00f1os por el agua, pero la mayor parte del recinto de la iglesia se ha secado, se ha erradicado el moho y est\u00e1n celebrando servicios de nuevo. Durante la tormenta y despu\u00e9s de ella, la iglesia aloj\u00f3 a familias sin hogar, y tambi\u00e9n acogi\u00f3 a algunos residentes de la zona cuyas casas hab\u00edan perdido el tejado.<\/p>\n<p>Un mes despu\u00e9s de la tormenta, las necesidades siguen siendo grandes, pero han pasado del refugio al sustento. \"Hab\u00eda puestos de comida por todas partes\", dijo Havlicek. \"No me di cuenta de que muchas de estas personas no tienen transporte para llegar a los puestos de comida y no ten\u00edan conciencia de llegar a ellos\". Cuando a\u00fan no hab\u00eda colegio, los padres y tutores ten\u00edan que volver al trabajo, muchos en empleos mal pagados, por horas, que requieren su asistencia para cobrar. Descubrimos que muchos ni\u00f1os que depend\u00edan de las comidas gratuitas o de bajo coste en las escuelas estaban solos en casa sin nada que comer. Trabajamos con el sistema escolar para identificar las zonas donde viv\u00edan muchos de estos ni\u00f1os; luego recogimos alimentos aptos para ni\u00f1os y los llevamos a los barrios para distribuirlos.\"<\/p>\n<p>Es posible que muchas de estas familias no tengan seguro, o quiz\u00e1 no el suficiente para pagar los da\u00f1os. Tambi\u00e9n es posible que a\u00fan se est\u00e9n recuperando de otras tormentas en la zona. Todos esos factores hacen que sus trabajos sean vitales para la supervivencia de sus familias.<\/p>\n<p><a href=\"https:\/\/www.firstpresmhc.org\/\">Primer Presbiteriano de Morehead City<\/a> le gustar\u00eda acoger equipos de trabajo, y Havlicek lo ve como el siguiente paso de la iglesia para contribuir a la recuperaci\u00f3n a largo plazo. Agradece a Presbyterian Disaster Assistance su ayuda para evaluar los da\u00f1os y determinar los pasos a seguir. \"Fueron fant\u00e1sticos al venir r\u00e1pidamente y reunirse con los pastores y las iglesias para ver c\u00f3mo est\u00e1bamos y decirnos los pasos a seguir\", dijo Havlicek. \"Ahora estamos preparados para reunirnos con otro grupo de respuesta. Nos gustar\u00eda convertirnos en un equipo de recuperaci\u00f3n a largo plazo, y vienen para evaluar la situaci\u00f3n y ver si tenemos lo que hace falta. Creemos que estamos preparados. Nos dicen que es una gran responsabilidad\".<\/p>\n<div id=\"attachment_6198\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/Doug-photo-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6198\" class=\"wp-image-6198 size-medium\" src=\"http:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/Doug-photo-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><p id=\"caption-attachment-6198\" class=\"wp-caption-text\">El reverendo Dr. Doug Cushing tom\u00f3 esta foto de unos escombros frente a una casa en Carolina del Norte.<\/p><\/div>\n<p><strong>El condado de Duplin fue duramente golpeado<\/strong><\/p>\n<p>En Wallace, Carolina del Norte, el reverendo Dr. Phil Gladden (conocido por los lugare\u00f1os como \"Dr. Phil\") dijo que al menos 35 miembros de su congregaci\u00f3n, <a href=\"http:\/\/wallacepresbyterian.com\/\">Iglesia Presbiteriana de Wallace<\/a>perdieron sus casas y todo lo que hab\u00eda en ellas cuando se inund\u00f3 una subdivisi\u00f3n cercana. Gladden se encontraba en Zambia disfrutando de un a\u00f1o sab\u00e1tico cuando el hurac\u00e1n Florence inici\u00f3 su lenta marcha hacia su casa en el condado de Duplin. Acort\u00f3 su viaje y su a\u00f1o sab\u00e1tico, llegando a casa una hora antes de que el hurac\u00e1n golpeara. La Rev. Dra. Nancy Gladden, del Presbiterio de Carolina Costera, es su esposa.<\/p>\n<p>Tras haber sufrido el hurac\u00e1n Floyd en 1999, sab\u00eda lo que se avecinaba y quer\u00eda estar all\u00ed para ayudar. En cuanto amain\u00f3 la tormenta, empez\u00f3 a enviar mensajes de texto y a llamar a cada miembro de su iglesia para evaluar qu\u00e9 necesitaban y c\u00f3mo pod\u00eda ayudar la iglesia. \"Supongo que una de las cosas que m\u00e1s me ha llenado de humildad es que algunas de las personas de nuestra iglesia que perdieron sus casas fueron de las primeras en dar un paso al frente para organizar los esfuerzos de ayuda a otras personas\", dijo Phil Gladden. \"Es impresionante\".<\/p>\n<p>Tambi\u00e9n se pregunta si la gente dejar\u00e1 Wallace y no volver\u00e1. \"Creo que va a cambiar esta iglesia\", dijo Phil Gladden. \"Me preocupa que algunas personas se marchen y no vuelvan.  Creo que va a afectar a la econom\u00eda de este pueblo\".<\/p>\n<p><strong>Nueva comunidad de culto<\/strong><\/p>\n<p>Wilmington, Carolina del Norte, fue una de las ciudades m\u00e1s afectadas por Florence. El reverendo Dr. Doug Cushing, pastor de <a href=\"https:\/\/www.thebridgepres.org\/\">Iglesia Presbiteriana The Bridge<\/a> de la cercana Leland, Carolina del Norte, afirma que su iglesia est\u00e1 muy implicada en la misi\u00f3n de la comunidad, y que lo est\u00e1 a\u00fan m\u00e1s despu\u00e9s de Florencia. Su congregaci\u00f3n es una de las 1001 Nuevas Comunidades de Culto.<\/p>\n<p>\"Los miembros de nuestra congregaci\u00f3n -nos llamamos el club de la lona azul- han perdido vallas y \u00e1rboles, pero nadie ha perdido su casa\", dijo Cushing. \"F\u00edsicamente nos ha ido bastante bien, pero emocionalmente esto nos ha pasado una gran factura por la devastaci\u00f3n en nuestra comunidad\".<\/p>\n<p>Su iglesia est\u00e1 recogiendo material escolar para que, cuando reabran las escuelas, los ni\u00f1os puedan volver a estudiar con los art\u00edculos que necesitan. La iglesia tambi\u00e9n tiene un ministerio que teje a ganchillo esteras de dormir para los sin techo con bolsas de pl\u00e1stico. Esa labor contin\u00faa con m\u00e1s intensidad. La iglesia tambi\u00e9n participa dos veces por semana en la distribuci\u00f3n de alimentos a los que se est\u00e1n recuperando de Florence. Y su banda de alabanza organiz\u00f3 una recaudaci\u00f3n de fondos en un pub irland\u00e9s local, con la que recaud\u00f3 $8.000 para ayudar a la recuperaci\u00f3n.<\/p>\n<p>Lo dif\u00edcil, dijo, es esperar a que comience la siguiente etapa de la vida tras el paso de Florence. \"Muchas de las personas que han perdido sus hogares est\u00e1n pasando por la reparaci\u00f3n del moho, y hasta que no se elimine el moho, no es seguro para muchos voluntarios\", dijo Cushing. \"Es el tiempo intermedio\".<\/p>","protected":false},"excerpt":{"rendered":"<p>Las congregaciones del presbiterio est\u00e1n luchando<\/p>","protected":false},"author":38,"featured_media":46618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[385,386,187],"class_list":["post-6195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-coastal-carolina-presbytery","tag-hurricane-florance","tag-presbyterian-disaster-assistance"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Congregations in the presbytery are struggling\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Robyn Davis Sekula\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Presbyterian Foundation -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation\" \/>\n\t\t<meta property=\"og:description\" content=\"Congregations in the presbytery are struggling\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-12T17:38:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-16T20:11:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PCUSAFoundation\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@PCUSAFoundation\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Congregations in the presbytery are struggling\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@PCUSAFoundation\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#blogposting\",\"name\":\"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation\",\"headline\":\"Coastal Carolina Presbytery recovers from Hurricane\",\"author\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/author\\\/robyn\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/News-Story-2-coastal-carolina.png\",\"width\":1920,\"height\":1282},\"datePublished\":\"2018-10-12T13:38:17-04:00\",\"dateModified\":\"2024-07-16T16:11:10-04:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#webpage\"},\"articleSection\":\"News, Coastal Carolina Presbytery, Hurricane Florance, Presbyterian Disaster Assistance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#listItem\",\"name\":\"Coastal Carolina Presbytery recovers from Hurricane\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#listItem\",\"position\":3,\"name\":\"Coastal Carolina Presbytery recovers from Hurricane\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/#organization\",\"name\":\"Presbyterian Foundation\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PCUSAFoundation\",\"https:\\\/\\\/twitter.com\\\/PCUSAFoundation\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/PCUSAfoundation\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/author\\\/robyn\\\/#author\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/author\\\/robyn\\\/\",\"name\":\"Robyn Davis Sekula\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#webpage\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/\",\"name\":\"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation\",\"description\":\"Congregations in the presbytery are struggling\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/author\\\/robyn\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/author\\\/robyn\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/News-Story-2-coastal-carolina.png\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#mainImage\",\"width\":1920,\"height\":1282},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/resources\\\/news\\\/coastal-carolina-presbytery-recovers-from-hurricane-florence\\\/#mainImage\"},\"datePublished\":\"2018-10-12T13:38:17-04:00\",\"dateModified\":\"2024-07-16T16:11:10-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/\",\"name\":\"Presbyterian Foundation\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.presbyterianfoundation.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Presbiterio de Carolina del Costa se recupera del hurac\u00e1n - Fundaci\u00f3n Presbiteriana","description":"Las congregaciones del presbiterio est\u00e1n luchando","canonical_url":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#blogposting","name":"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation","headline":"Coastal Carolina Presbytery recovers from Hurricane","author":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/author\/robyn\/#author"},"publisher":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/News-Story-2-coastal-carolina.png","width":1920,"height":1282},"datePublished":"2018-10-12T13:38:17-04:00","dateModified":"2024-07-16T16:11:10-04:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#webpage"},"isPartOf":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#webpage"},"articleSection":"News, Coastal Carolina Presbytery, Hurricane Florance, Presbyterian Disaster Assistance"},{"@type":"BreadcrumbList","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es#listItem","position":1,"name":"Home","item":"https:\/\/www.presbyterianfoundation.org\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/#listItem","position":2,"name":"News","item":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#listItem","name":"Coastal Carolina Presbytery recovers from Hurricane"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#listItem","position":3,"name":"Coastal Carolina Presbytery recovers from Hurricane","previousItem":{"@type":"ListItem","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/www.presbyterianfoundation.org\/es\/#organization","name":"Presbyterian Foundation","url":"https:\/\/www.presbyterianfoundation.org\/es\/","sameAs":["https:\/\/www.facebook.com\/PCUSAFoundation","https:\/\/twitter.com\/PCUSAFoundation","https:\/\/www.linkedin.com\/company\/PCUSAfoundation"]},{"@type":"Person","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/author\/robyn\/#author","url":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/author\/robyn\/","name":"Robyn Davis Sekula"},{"@type":"WebPage","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#webpage","url":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/","name":"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation","description":"Congregations in the presbytery are struggling","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#breadcrumblist"},"author":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/author\/robyn\/#author"},"creator":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/author\/robyn\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.presbyterianfoundation.org\/wp-content\/uploads\/2018\/10\/News-Story-2-coastal-carolina.png","@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#mainImage","width":1920,"height":1282},"primaryImageOfPage":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/#mainImage"},"datePublished":"2018-10-12T13:38:17-04:00","dateModified":"2024-07-16T16:11:10-04:00"},{"@type":"WebSite","@id":"https:\/\/www.presbyterianfoundation.org\/es\/#website","url":"https:\/\/www.presbyterianfoundation.org\/es\/","name":"Presbyterian Foundation","inLanguage":"es-MX","publisher":{"@id":"https:\/\/www.presbyterianfoundation.org\/es\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Presbyterian Foundation -","og:type":"article","og:title":"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation","og:description":"Congregations in the presbytery are struggling","og:url":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/","article:published_time":"2018-10-12T17:38:17+00:00","article:modified_time":"2024-07-16T20:11:10+00:00","article:publisher":"https:\/\/www.facebook.com\/PCUSAFoundation","twitter:card":"summary","twitter:site":"@PCUSAFoundation","twitter:title":"Coastal Carolina Presbytery recovers from Hurricane - Presbyterian Foundation","twitter:description":"Congregations in the presbytery are struggling","twitter:creator":"@PCUSAFoundation"},"aioseo_meta_data":{"post_id":"6195","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-01-29 07:01:10","updated":"2025-06-13 22:20:33","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.presbyterianfoundation.org\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoastal Carolina Presbytery recovers from Hurricane\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.presbyterianfoundation.org\/es"},{"label":"News","link":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/category\/news\/"},{"label":"Coastal Carolina Presbytery recovers from Hurricane","link":"https:\/\/www.presbyterianfoundation.org\/es\/resources\/news\/coastal-carolina-presbytery-recovers-from-hurricane-florence\/"}],"_links":{"self":[{"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/posts\/6195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/comments?post=6195"}],"version-history":[{"count":0,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/posts\/6195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/media\/46618"}],"wp:attachment":[{"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/media?parent=6195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/categories?post=6195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.presbyterianfoundation.org\/es\/wp-json\/wp\/v2\/tags?post=6195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}